{"id":189,"count":11,"description":"","link":"https:\/\/devtest.msxi.com\/zh-hans\/category\/timeline-02-zh-hans\/","name":"Timeline 02-DE","slug":"timeline-02-zh-hans","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Timeline 02-DE Archives - MSXI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Timeline 02-DE Archives - MSXI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/\" \/>\n<meta property=\"og:site_name\" content=\"MSXI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/\",\"url\":\"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/\",\"name\":\"Timeline 02-DE Archives - MSXI\",\"isPartOf\":{\"@id\":\"https:\/\/devtest.msxi.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/devtest.msxi.com\/zh-hans\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Timeline 02-CORP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/devtest.msxi.com\/en\/#website\",\"url\":\"https:\/\/devtest.msxi.com\/en\/\",\"name\":\"MSXI\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/devtest.msxi.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Timeline 02-DE Archives - MSXI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/","og_locale":"zh_CN","og_type":"article","og_title":"Timeline 02-DE Archives - MSXI","og_url":"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/","og_site_name":"MSXI","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/","url":"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/","name":"Timeline 02-DE Archives - MSXI","isPartOf":{"@id":"https:\/\/devtest.msxi.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/#breadcrumb"},"inLanguage":"zh-Hans"},{"@type":"BreadcrumbList","@id":"https:\/\/devtest.msxi.com\/en\/category\/timeline-02-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/devtest.msxi.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Timeline 02-CORP"}]},{"@type":"WebSite","@id":"https:\/\/devtest.msxi.com\/en\/#website","url":"https:\/\/devtest.msxi.com\/en\/","name":"MSXI","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/devtest.msxi.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"_links":{"self":[{"href":"https:\/\/devtest.msxi.com\/zh-hans\/wp-json\/wp\/v2\/categories\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devtest.msxi.com\/zh-hans\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/devtest.msxi.com\/zh-hans\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/devtest.msxi.com\/zh-hans\/wp-json\/wp\/v2\/posts?categories=189"},{"href":"https:\/\/devtest.msxi.com\/zh-hans\/wp-json\/wp\/v2\/pages?categories=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}